{"id":348,"date":"2024-09-18T21:31:49","date_gmt":"2024-09-18T21:31:49","guid":{"rendered":"https:\/\/naturales.ues.edu.sv\/matematica\/?p=348"},"modified":"2024-09-18T21:32:10","modified_gmt":"2024-09-18T21:32:10","slug":"escuela-de-matematica-realiza-exposicion-de-posteres","status":"publish","type":"post","link":"https:\/\/naturales.ues.edu.sv\/matematica\/2024\/09\/18\/escuela-de-matematica-realiza-exposicion-de-posteres\/","title":{"rendered":"Escuela de Matem\u00e1tica realiza exposici\u00f3n de p\u00f3steres"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Escuela de Matem\u00e1tica de la Facultad de Ciencias Naturales y Matem\u00e1tica, realiza la exposici\u00f3n de p\u00f3steres investigativos realizados por personal docente de la Escuela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estudiantes pueden consultar su informaci\u00f3n de los temas: \u201cPrincipal Line son an Ellipsoid in a Minkoswki Three-Dimensional Space\u201d por el director de la Escuela de Matem\u00e1tica, Dr. Dimas Tejada; \u201cConstrucci\u00f3n de cuasigrupo y lazos a partir de otras estructuras algebraicas y\/o topol\u00f3gicas\u201d por la Dra. Ingrid Mart\u00ednez y el M.Sc. Juan Rivera; y \u201cParque vehicular en San Salvador y alrededores: Proyecciones\u201d por el M.Sc. Otoniel Campos Granados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos p\u00f3steres fueron presentados durante el evento de conmemoraci\u00f3n de los 33 a\u00f1os de fundaci\u00f3n de la Facultad de Ciencias Naturales y Matem\u00e1tica y estar\u00e1n disponibles durante toda la semana en el pasillo de la Escuela de Matem\u00e1tica.<\/p>\n\n\n<style id=\"wp_carousel_dynamic_css350\">.sp-wp-carousel-free-id-350.wpcf-fancybox-wrapper .fancybox-bg{background: #0b0b0b;opacity: 0.8;}.sp-wp-carousel-free-id-350.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button .wpcp-fancybox-nav-arrow i {color: #ccc;}.sp-wp-carousel-free-id-350.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button .wpcp-fancybox-nav-arrow i:hover {color: #fff;}.sp-wp-carousel-free-id-350.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button {background: #1e1e1e;}.sp-wp-carousel-free-id-350.wpcf-fancybox-wrapper .fancybox-navigation .fancybox-button:hover {background: #1e1e1e;}#sp-wp-carousel-free-id-350 .wpcp-swiper-dots {margin: 40px 0px 0px 0px;}.wpcp-wrapper-350 .swiper-wrapper .swiper-slide-kenburn, .wpcp-wrapper-350 .swiper-wrapper, .wpcp-wrapper-350 .wpcpro-row{align-items: center;}#sp-wp-carousel-free-id-350 .wpcp-single-item {box-shadow: 0px 0px 0px 0px #dddddd;transition: all .3s;margin: 0px;}#sp-wp-carousel-free-id-350.swiper-flip .wpcp-single-item{margin: 0!important;}#sp-wp-carousel-free-id-350 .wpcp-single-item:hover {box-shadow: 0px 0px 0px 0px #dddddd;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .wpcp-single-item {border: 1px solid #dddddd;}#sp-wp-carousel-free-id-350.wpcp-carousel-section.sp-wpcp-350 .swiper-button-prev,#sp-wp-carousel-free-id-350.wpcp-carousel-section.sp-wpcp-350 .swiper-button-next,#sp-wp-carousel-free-id-350.wpcp-carousel-section.sp-wpcp-350 .swiper-button-prev:hover,#sp-wp-carousel-free-id-350.wpcp-carousel-section.sp-wpcp-350 .swiper-button-next:hover {font-size: 18px ; font-weight: 400;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-prev,#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-next,#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-prev:hover,#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-next:hover {background: none;border: none;font-size: 30px;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-prev i,#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-next i {color: #aaa;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-prev i:hover,#sp-wp-carousel-free-id-350.sp-wpcp-350 .swiper-button-next i:hover {color: #178087;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .wpcp-swiper-dots .swiper-pagination-bullet {background-color: #cccccc;}#sp-wp-carousel-free-id-350.sp-wpcp-350 .wpcp-swiper-dots .swiper-pagination-bullet.swiper-pagination-bullet-active {background-color: #178087;} #sp-wp-carousel-free-id-350.sp-wpcp-350.wpcp-image-carousel .wpcp-single-item:hover img, #sp-wp-carousel-free-id-350.sp-wpcp-350.wpcp-post-carousel .wpcp-single-item:hover img, #sp-wp-carousel-free-id-350.sp-wpcp-350.wpcp-product-carousel .wpcp-single-item:hover img{-webkit-transform: scale(1.2);-moz-transform: scale(1.2);transform: scale(1.2);}#sp-wp-carousel-free-id-350 .wpcpro-row>[class*=\"wpcpro-col-\"] { padding: 0 10px; padding-bottom: 20px;} #sp-wp-carousel-free-id-350 .swiper-slide .single-item-fade:not(:last-child) { margin-right: 20px;}@media (min-width: 480px) { .wpcpro-row .wpcpro-col-sm-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-sm-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-sm-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-sm-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-sm-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-sm-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-sm-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-sm-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-sm-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (max-width: 480px) { .wpcpro-row .wpcpro-col-xs-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xs-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xs-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-xs-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xs-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xs-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-xs-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xs-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 736px) { .wpcpro-row .wpcpro-col-md-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-md-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-md-2-5 { flex: 0 0 75%; max-width: 75%; } .wpcpro-row .wpcpro-col-md-3 { flex: 0 0 33.333%; max-width: 33.333%; } .wpcpro-row .wpcpro-col-md-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-md-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-md-6 { flex: 0 0 16.66666666666667%; max-width: 16.66666666666667%; } .wpcpro-row .wpcpro-col-md-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-md-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 980px) { .wpcpro-row .wpcpro-col-lg-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-lg-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-lg-3 { flex: 0 0 33.222%; max-width: 33.222%; } .wpcpro-row .wpcpro-col-lg-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-lg-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-lg-6 { flex: 0 0 16.6667%; max-width: 16.6667%; } .wpcpro-row .wpcpro-col-lg-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-lg-8 { flex: 0 0 12.5%; max-width: 12.5%; } } @media (min-width: 1200px) { .wpcpro-row .wpcpro-col-xl-1 { flex: 0 0 100%; max-width: 100%; } .wpcpro-row .wpcpro-col-xl-2 { flex: 0 0 50%; max-width: 50%; } .wpcpro-row .wpcpro-col-xl-3 { flex: 0 0 33.22222222%; max-width: 33.22222222%; } .wpcpro-row .wpcpro-col-xl-4 { flex: 0 0 25%; max-width: 25%; } .wpcpro-row .wpcpro-col-xl-5 { flex: 0 0 20%; max-width: 20%; } .wpcpro-row .wpcpro-col-xl-6 { flex: 0 0 16.66667%; max-width: 16.66667%; } .wpcpro-row .wpcpro-col-xl-7 { flex: 0 0 14.28571428%; max-width: 14.28571428%; } .wpcpro-row .wpcpro-col-xl-8 { flex: 0 0 12.5%; max-width: 12.5%; } }<\/style><div class=\"wpcp-carousel-wrapper wpcp-wrapper-350\">\n\t<div id=\"wpcp-preloader-350\" class=\"wpcp-carousel-preloader\"><img decoding=\"async\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/plugins\/wp-carousel-free\/public\/css\/spinner.svg\" alt=\"Preloader Image\" \/><\/div>\t<div class=\"wpcp-carousel-content-wrapper\">\n\t<div id=\"sp-wp-carousel-free-id-350\" class=\"wpcp-carousel-section sp-wpcp-350  nav-vertical-center wpcp-image-carousel wpcp-preloader wpcp-standard\" data-swiper='{ &quot;pagination_type&quot;: &quot;dots&quot;,&quot;accessibility&quot;:true, &quot;spaceBetween&quot;:20, &quot;arrows&quot;:true, &quot;freeMode&quot;: false, &quot;autoplay&quot;:true, &quot;effect&quot;: &quot;&quot;, &quot;centerMode&quot;: false, &quot;autoplaySpeed&quot;:3000, &quot;dots&quot;:true, &quot;infinite&quot;:true, &quot;speed&quot;:600, &quot;pauseOnHover&quot;:true,\n\t\t\t&quot;slidesToShow&quot;:{&quot;lg_desktop&quot;:5, &quot;desktop&quot;: 4, &quot;laptop&quot;: 3, &quot;tablet&quot;: 2, &quot;mobile&quot;: 1}, &quot;responsive&quot;:{&quot;desktop&quot;:1200, &quot;laptop&quot;: 980, &quot;tablet&quot;: 736, &quot;mobile&quot;: 480}, &quot;rtl&quot;:false, &quot;lazyLoad&quot;: &quot;false&quot;, &quot;swipe&quot;: true, &quot;draggable&quot;: true, &quot;swipeToSlide&quot;:false }' dir=\"ltr\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0486.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0486.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0486.jpg\" alt=\"IMG_0486\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0485.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0485.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0485.jpg\" alt=\"IMG_0485\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0484.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0484.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0484.jpg\" alt=\"IMG_0484\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0482.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0482.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0482.jpg\" alt=\"IMG_0482\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0476.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0476.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0476.jpg\" alt=\"IMG_0476\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0474.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0474.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0474.jpg\" alt=\"IMG_0474\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0472.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0472.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0472.jpg\" alt=\"IMG_0472\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0470.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0470.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0470.jpg\" alt=\"IMG_0470\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t<div class=\"swiper-slide\">\n\t<div class=\"wpcp-single-item\">\n\t\t\t<a class=\"wcp-light-box\" data-buttons='[\"close\"]' data-wpc_url='https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0465.jpg' href=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0465.jpg\" data-fancybox=\"wpcp_view\">\n\t\t<figure>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"skip-lazy\" src=\"https:\/\/naturales.ues.edu.sv\/matematica\/wp-content\/uploads\/sites\/24\/2024\/09\/IMG_0465.jpg\" alt=\"IMG_0465\" width=\"300\" height=\"200\">\t\t<\/figure>\n\t<\/a>\n\t\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wpcp-swiper-dots swiper-pagination\"><\/div>\n\t\t\t\t<!-- If we need navigation buttons -->\n\t\t\t\t\t<div class=\"wpcp-prev-button swiper-button-prev\"><i class=\"fa fa-angle-left\"><\/i><\/div>\n\t\t\t<div class=\"wpcp-next-button swiper-button-next\"><i class=\"fa fa-angle-right\"><\/i><\/div>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>La Escuela de Matem\u00e1tica de la Facultad de Ciencias Naturales y Matem\u00e1tica, realiza la exposici\u00f3n de p\u00f3steres investigativos realizados por personal docente de la Escuela. Los estudiantes pueden consultar su&hellip;<\/p>\n","protected":false},"author":4,"featured_media":355,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/posts\/348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":1,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"predecessor-version":[{"id":360,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/posts\/348\/revisions\/360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/media\/355"}],"wp:attachment":[{"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/matematica\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}