{"id":194,"date":"2025-07-11T23:10:04","date_gmt":"2025-07-11T21:10:04","guid":{"rendered":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/?p=194"},"modified":"2025-07-17T23:25:55","modified_gmt":"2025-07-17T21:25:55","slug":"jueves-17","status":"publish","type":"post","link":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/2025\/07\/11\/jueves-17\/","title":{"rendered":"Jueves 17"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/meet.google.com\/apc-ebis-nnk\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"963\" src=\"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-1024x963.jpg\" alt=\"\" class=\"wp-image-211\" srcset=\"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-1024x963.jpg 1024w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-300x282.jpg 300w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-768x722.jpg 768w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-Mate-y-su-didactica-2025_Mesa-de-trabajo-1.jpg 1149w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/meet.google.com\/mqv-qkcu-aar\"><img decoding=\"async\" width=\"1024\" height=\"963\" src=\"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-tarde-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-1024x963.png\" alt=\"\" class=\"wp-image-213\" srcset=\"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-tarde-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-1024x963.png 1024w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-tarde-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-300x282.png 300w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-tarde-Mate-y-su-didactica-2025_Mesa-de-trabajo-1-768x722.png 768w, https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-content\/uploads\/sites\/37\/2025\/07\/enlaces-jueves-tarde-Mate-y-su-didactica-2025_Mesa-de-trabajo-1.png 1149w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-194","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/posts\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":3,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/posts\/194\/revisions"}],"predecessor-version":[{"id":215,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/posts\/194\/revisions\/215"}],"wp:attachment":[{"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/media?parent=194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/categories?post=194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naturales.ues.edu.sv\/mydidactica2025\/wp-json\/wp\/v2\/tags?post=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}